{"id":6438,"date":"2026-02-16T14:44:10","date_gmt":"2026-02-16T13:44:10","guid":{"rendered":"https:\/\/www.sources-hotels.com\/bourgogne\/?page_id=6438"},"modified":"2026-08-07T15:24:28","modified_gmt":"2026-08-07T13:24:28","slug":"restaurant-le-clos-de-la-tour","status":"publish","type":"page","link":"https:\/\/www.sources-hotels.com\/bourgogne\/restaurant-le-clos-de-la-tour\/","title":{"rendered":"Restaurant Le Clos de la Tour"},"content":{"rendered":"\n<section class=\"custom-block block--header aspect-[375\/700] text-center text-white overflow-hidden pt-[100rem] relative tablet:aspect-auto tablet:h-[700rem] tablet:pt-[420rem]\">\n\n    <h1>\n                            Le Clos de la Tour            <\/h1>\n\n    \n    <span class=\"scroll-down hidden text-[12rem] tracking-[2rem] uppercase font-title cursor-pointer opacity-[64%] pb-[66rem] absolute left-2\/4 bottom-0 translate-x-[-50%] after:w-[1px] after:h-[50rem] after:bg-white after:opacity-[40%] after:absolute after:bottom-0 after:left-[50%] tablet:block\">\n        Voir la suite    <\/span>\n\n    <figure class=\"min-w-full min-h-full aspect-video overflow-hidden absolute top-2\/4 left-2\/4 translate-x-[-50%] translate-y-[-50%] z-[-1] before:bg-black before:opacity-[35%] before:mix-blend-multiply before:absolute before:top-0 before:left-0 before:right-0 before:bottom-0 before:z-[2]\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"2880\" height=\"1800\" src=\"https:\/\/www.sources-hotels.com\/bourgogne\/wp-content\/uploads\/sites\/5\/2026\/02\/Le-Clos-de-la-Tour-2880x1800.jpg\" class=\"h-full w-full object-cover object-center\" alt=\"Le Clos de la Tour restaurant Vougeot\" \/>            <\/figure>\n\n        \n<\/section>\n\n    \n\n\n<section class=\"custom-block block--restaurant-details\">\n  <div class=\"row-details row-1\">\n          <div class=\"hour icon-text\">\n        <svg width=\"20\" height=\"20\" viewBox=\"0 0 20 20\" fill=\"none\"><use xlink:href=\"#clock\"\/><\/svg><p>Ouvert du Mercredi au dimanche soir : 19h00-21h15<br \/>\nSamedi &amp; dimanche midi : 12h00-13h30<\/p>\n      <\/div>\n              <div class=\"mail icon-text\">Informations : <a href=\"mailto:reservations@sources-vougeot.com\">reservations@sources-vougeot.com<\/a><\/div>\n    \n          <div class=\"phone icon-text\">T\u00e9l : <a href=\"tel:+33 (0)3 80 23 22 22\">+33 (0)3 80 23 22 22<\/a><\/div>\n      <\/div>\n      <div class=\"row-details row-2\">\n              <div class=\"link-details\">\n            <a href=\"https:\/\/www.sources-hotels.com\/bourgogne\/wp-content\/uploads\/sites\/5\/2026\/02\/Menu-FR-Le-Clos-de-la-Tour.pdf\"  target=\"_blank\" class=\"cta-resto-details\" >\n          <span class=\"picto\"><svg width=\"14\" height=\"13\" viewBox=\"0 0 14 13\" fill=\"none\"><use xlink:href=\"#download\"\/><\/svg><\/span>\n        Menu Le Clos de la Tour  <\/a>\n        <\/div>\n              <div class=\"link-details\">\n            <a href=\"https:\/\/www.sources-hotels.com\/bourgogne\/wp-content\/uploads\/sites\/5\/2026\/03\/Le-Clos-de-la-Tour-Cartes-Vins.pdf\"  target=\"_blank\" class=\"cta-resto-details\" >\n          <span class=\"picto\"><svg width=\"14\" height=\"13\" viewBox=\"0 0 14 13\" fill=\"none\"><use xlink:href=\"#download\"\/><\/svg><\/span>\n        Carte des vins  <\/a>\n        <\/div>\n          <\/div>\n  <\/section>\n\n\n<section\n    class=\"custom-block block--large-visual-centered-text-white-background has-visual\">\n\n            <div class=\"large-visual-container\">\n\n            <div class=\"large-visual lightGallery\">\n                <figure>\n                    <img loading=\"lazy\" decoding=\"async\" width=\"1536\" height=\"784\" src=\"https:\/\/www.sources-hotels.com\/bourgogne\/wp-content\/uploads\/sites\/5\/2026\/02\/Chef-Julien-.png\" class=\"h-full w-full object-cover object-center lightgallery-item\" alt=\"Chef Julien Martin\" data-src=\"https:\/\/www.sources-hotels.com\/bourgogne\/wp-content\/uploads\/sites\/5\/2026\/02\/Chef-Julien-.png\" srcset=\"https:\/\/www.sources-hotels.com\/bourgogne\/wp-content\/uploads\/sites\/5\/2026\/02\/Chef-Julien-.png 1536w, https:\/\/www.sources-hotels.com\/bourgogne\/wp-content\/uploads\/sites\/5\/2026\/02\/Chef-Julien--300x153.png 300w, https:\/\/www.sources-hotels.com\/bourgogne\/wp-content\/uploads\/sites\/5\/2026\/02\/Chef-Julien--1024x523.png 1024w, https:\/\/www.sources-hotels.com\/bourgogne\/wp-content\/uploads\/sites\/5\/2026\/02\/Chef-Julien--768x392.png 768w\" sizes=\"auto, (max-width: 1536px) 100vw, 1536px\" \/>                <\/figure>\n            <\/div>\n\n                            <div class=\"titles\">\n\n                                            <h2 class=\"title\">Le Chef<\/h2>\n                    \n                                            <div class=\"watermark\">Julien Martin<\/div>\n                    \n                <\/div>\n            \n                        \n        <\/div>\n    \n    <div class=\"bloc-content\">\n                    <h3 class=\"title\">Une cuisine contemporaine, vivante et g\u00e9n\u00e9reuse<\/h3>\n                <div class=\"content rte\">\n            <p data-start=\"91\" data-end=\"422\">Bourguignon d\u2019origine, le Chef Julien Martin puise son inspiration dans le terroir qui l\u2019a vu na\u00eetre.<\/p>\n<p data-start=\"91\" data-end=\"422\">Form\u00e9 \u00e0 l\u2019excellence, notamment aupr\u00e8s du Chef doublement \u00e9toil\u00e9 Nicolas Masse aux Sources de Caudalie, il y d\u00e9veloppe une approche sensible et exigeante du produit, guid\u00e9e par la justesse du go\u00fbt et le respect des saisons.<\/p>\n<p data-start=\"429\" data-end=\"913\" data-is-last-node=\"\">Au Clos de la Tour, sa cuisine authentique et raffin\u00e9e rend un hommage sinc\u00e8re \u00e0 la Bourgogne, o\u00f9 chaque cr\u00e9ation trouve naturellement son prolongement dans la splendide cave du restaurant. Sublim\u00e9s par une carte des vins remarquable, m\u00ealant grands crus et cuv\u00e9es plus confidentielles, ses plats composent une exp\u00e9rience compl\u00e8te, \u00e0 la crois\u00e9e de l\u2019histoire mill\u00e9naire du lieu et d\u2019une modernit\u00e9 d\u00e9licate, laissant au palais un souvenir inoubliable.<\/p>\n        <\/div>\n\n                    <div class=\"cta-wrapper text-center\">\n                <a href=\"https:\/\/bookings.zenchef.com\/results?rid=385527&#038;pid=1001\" target=\"_blank\"\n                    class=\"button mt-[23rem] tablet:mt-[40rem]\">\n                    R\u00e9server une table                <\/a>\n            <\/div>\n            <\/div>\n\n    \n            <svg width=\"475\" height=\"889\" viewBox=\"0 0 475 889\" fill=\"none\"><use xlink:href=\"#leaf-side\"\/><\/svg>    \n<\/section>\n\n\n<section class=\"custom-block block--cooking-classes bg-primary\">\n\n            <h2 class=\"block-title\">Le Clos de la Tour<\/h2>\n    \n    <div class=\"content-wrapper picture-left\">\n\n        <div class=\"text\">\n\n                            <h4 class=\"subtitle\">Le restaurant gastronomique<\/h4>\n            \n                            <div class=\"content rte\">\n                    <p data-start=\"83\" data-end=\"460\">Chaque d\u00eener devient une parenth\u00e8se hors du temps, port\u00e9e par une atmosph\u00e8re intimiste et feutr\u00e9e. Le Chef Julien Martin d\u00e9ploie une cuisine contemporaine, vivante et g\u00e9n\u00e9reuse, inspir\u00e9e par la richesse des produits de la r\u00e9gion.<\/p>\n<p data-start=\"83\" data-end=\"460\">Dans chaque assiette, l\u2019esth\u00e9tique s\u2019accorde \u00e0 la pr\u00e9cision des saveurs pour offrir une exp\u00e9rience aussi belle que juste.<\/p>\n<p data-start=\"467\" data-end=\"646\" data-is-last-node=\"\">L\u2019\u00e2me d\u2019une histoire mill\u00e9naire se marie \u00e0 la modernit\u00e9 d\u2019une cuisine raffin\u00e9e, laissant au palais un souvenir exquis et l\u2019irr\u00e9sistible envie de revenir.<\/p>\n<ul>\n<li data-start=\"1067\" data-end=\"1126\">Menu en 3 \u00e9tapes : 90\u20ac<\/li>\n<li data-start=\"1067\" data-end=\"1126\">Menu en 4 \u00e9tapes : 120 \u20ac<\/li>\n<li data-start=\"1067\" data-end=\"1126\">Menu en 6 \u00e9tapes : 180 \u20ac<\/li>\n<\/ul>\n                <\/div>\n            \n            \n            \n            \n            \n        <\/div>\n        <div class=\"relative lightGallery\">\n            <figure class=\"image\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"1260\" height=\"970\" src=\"https:\/\/www.sources-hotels.com\/bourgogne\/wp-content\/uploads\/sites\/5\/2026\/04\/SDV_ClosDelaTour_VanilleAgrumes_\u00a9AgencePancake-6-e1777465185484-1260x970.jpg\" class=\"h-full w-full object-cover object-center lightgallery-item\" alt=\"Vanille Agrumes - Clos de la Tour - Les Sources de Vougeot\" data-src=\"https:\/\/www.sources-hotels.com\/bourgogne\/wp-content\/uploads\/sites\/5\/2026\/04\/SDV_ClosDelaTour_VanilleAgrumes_\u00a9AgencePancake-6-e1777465185484.jpg\" \/>            <\/figure>\n                    <\/div>\n    <\/div>\n\n<\/section>\n\n\n<section class=\"custom-block block--cooking-classes bg-white\">\n\n            <h2 class=\"block-title\"> Un cadre intimiste<\/h2>\n    \n    <div class=\"content-wrapper picture-right\">\n\n        <div class=\"text\">\n\n            \n                            <div class=\"content rte\">\n                    <p>Dans cet \u00e9crin minimaliste aux r\u00e9miniscences monacales, Le Clos de la Tour offre une atmosph\u00e8re hors du temps.<\/p>\n<p>L\u2019\u00e9clairage est orchestr\u00e9 pour sculpter une ambiance en clair-obscur, o\u00f9 ombre et lumi\u00e8re subliment chaque d\u00e9tail, du grain du bois \u00e0 l&rsquo;\u00e9clat des mets.<\/p>\n<p>\u00c0 la tomb\u00e9e de la nuit,\u00a0la tour historique s\u2019\u00e9l\u00e8ve au pied du restaurant qui lui emprunte son identit\u00e9, s&rsquo;illumine pour parachever cette aura quasi mystique.<\/p>\n<p><strong>Les Accords Parfaits<\/strong><\/p>\n<p>Notre Chef Sommelier accompagne votre d\u00e9gustation \u00e0 travers une remarquable s\u00e9lection de vins, m\u00ealant grands crus de Bourgogne et cuv\u00e9es plus confidentielles, afin de cr\u00e9er des accords mets et vins d&rsquo;une pr\u00e9cision et d&rsquo;une \u00e9l\u00e9gance absolues.<\/p>\n<p>Deux exp\u00e9riences vous sont propos\u00e9es : un accord en 3 verres au tarif de <strong>90 \u20ac<\/strong>, ou un accord en 4 verres au tarif de <strong>120 \u20ac<\/strong>.<\/p>\n                <\/div>\n            \n            \n            \n            \n            \n        <\/div>\n        <div class=\"relative lightGallery\">\n            <figure class=\"image\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"1260\" height=\"1000\" src=\"https:\/\/www.sources-hotels.com\/bourgogne\/wp-content\/uploads\/sites\/5\/2026\/02\/Cadre-intimiste-Le-Clos-de-la-Tour-1260x1000.jpg\" class=\"h-full w-full object-cover object-center lightgallery-item\" alt=\"Clos de la Tour Restaurant\" data-src=\"https:\/\/www.sources-hotels.com\/bourgogne\/wp-content\/uploads\/sites\/5\/2026\/02\/Cadre-intimiste-Le-Clos-de-la-Tour.jpg\" \/>            <\/figure>\n                    <\/div>\n    <\/div>\n\n<\/section>\n\n<section class=\"custom-block block--three-visuals-cta mx-auto text-center\">\n\n                    <div class=\"images lightGallery\">\n                            <div class=\"relative\">\n                    <figure>\n                        <img loading=\"lazy\" decoding=\"async\" width=\"840\" height=\"600\" src=\"https:\/\/www.sources-hotels.com\/bourgogne\/wp-content\/uploads\/sites\/5\/2026\/03\/SDV_ClosDelaTour_RizdeVeau_\u00a9AgencePancake-3-e1774628460197-840x600.jpg\" class=\"w-full h-full object-cover object-center lightgallery-item\" alt=\"Riz de Veau - Le Clos de la Tour\" data-src=\"https:\/\/www.sources-hotels.com\/bourgogne\/wp-content\/uploads\/sites\/5\/2026\/03\/SDV_ClosDelaTour_RizdeVeau_\u00a9AgencePancake-3-e1774628460197.jpg\" \/>                    <\/figure>\n                                    <\/div>\n                            <div class=\"relative\">\n                    <figure>\n                        <img loading=\"lazy\" decoding=\"async\" width=\"840\" height=\"600\" src=\"https:\/\/www.sources-hotels.com\/bourgogne\/wp-content\/uploads\/sites\/5\/2026\/03\/SDV_ClosDelaTour_CroqueEscargot_\u00a9AgencePancake-3-e1774628580372-840x600.jpg\" class=\"w-full h-full object-cover object-center lightgallery-item\" alt=\"Croque d&#039;escargot Clos de la Tour\" data-src=\"https:\/\/www.sources-hotels.com\/bourgogne\/wp-content\/uploads\/sites\/5\/2026\/03\/SDV_ClosDelaTour_CroqueEscargot_\u00a9AgencePancake-3-e1774628580372.jpg\" \/>                    <\/figure>\n                                    <\/div>\n                            <div class=\"relative\">\n                    <figure>\n                        <img loading=\"lazy\" decoding=\"async\" width=\"840\" height=\"600\" src=\"https:\/\/www.sources-hotels.com\/bourgogne\/wp-content\/uploads\/sites\/5\/2026\/03\/SDV_ClosDelaTour_Saint-Jacques_\u00a9AgencePancake-e1774628657716-840x600.jpg\" class=\"w-full h-full object-cover object-center lightgallery-item\" alt=\"Resteaurant Les Sources de Vougeot\" data-src=\"https:\/\/www.sources-hotels.com\/bourgogne\/wp-content\/uploads\/sites\/5\/2026\/03\/SDV_ClosDelaTour_Saint-Jacques_\u00a9AgencePancake-e1774628657716.jpg\" \/>                    <\/figure>\n                                    <\/div>\n                    <\/div>\n    \n\n    \n\n\n\n<\/section>\n\n<section class=\"custom-block block--title-text\">\n\n    \n            <div class=\"text rte\"><p style=\"text-align: center;\"><em>Quelques d\u00e9licates attentions\u2026<\/em><br \/>\n<em>Une tenue soign\u00e9e est requise pour sublimer l\u2019exp\u00e9rience.<\/em><br \/>\n<em>Pour pr\u00e9server la qui\u00e9tude des lieux, les animaux ne sont pas autoris\u00e9s au sein de notre restaurant.<\/em><\/p>\n<\/div>\n    \n<\/section>\n\n\n\n<section class=\"custom-block block--slider-classic-pictures flex flex-col items-center background-theme-light\">\n\n            <h2 class=\"block-title\">Nos restaurants &#038; bar<\/h2>\n    \n    <div class=\"slides lightGallery w-[209rem] !overflow-visible self-start tablet:w-[990rem] tablet:relative tablet:left-[60rem]\">\n\n        \n            <div class=\"slide w-[200rem] tablet:w-[450rem] teaser teaser--article-type-1\">\n\n                \n                <figure class=\"w-full h-[240rem] mb-[5rem] tablet:h-[575rem] tablet:mb-[30rem]\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"1725\" height=\"1150\" src=\"https:\/\/www.sources-hotels.com\/bourgogne\/wp-content\/uploads\/sites\/5\/2026\/04\/SDV_LAubergedesCiteaux_\u00a9AgencePancake-11-1725x1150.jpg\" class=\"h-full w-full object-cover object-center lightgallery-item\" alt=\"Salle L&#039;Auberge des C\u00eeteaux - Les Sources de Vougeot\" data-src=\"https:\/\/www.sources-hotels.com\/bourgogne\/wp-content\/uploads\/sites\/5\/2026\/04\/SDV_LAubergedesCiteaux_\u00a9AgencePancake-11.jpg\" srcset=\"https:\/\/www.sources-hotels.com\/bourgogne\/wp-content\/uploads\/sites\/5\/2026\/04\/SDV_LAubergedesCiteaux_\u00a9AgencePancake-11-1725x1150.jpg 1725w, https:\/\/www.sources-hotels.com\/bourgogne\/wp-content\/uploads\/sites\/5\/2026\/04\/SDV_LAubergedesCiteaux_\u00a9AgencePancake-11-300x200.jpg 300w, https:\/\/www.sources-hotels.com\/bourgogne\/wp-content\/uploads\/sites\/5\/2026\/04\/SDV_LAubergedesCiteaux_\u00a9AgencePancake-11-1024x683.jpg 1024w, https:\/\/www.sources-hotels.com\/bourgogne\/wp-content\/uploads\/sites\/5\/2026\/04\/SDV_LAubergedesCiteaux_\u00a9AgencePancake-11-768x512.jpg 768w, https:\/\/www.sources-hotels.com\/bourgogne\/wp-content\/uploads\/sites\/5\/2026\/04\/SDV_LAubergedesCiteaux_\u00a9AgencePancake-11-1536x1024.jpg 1536w, https:\/\/www.sources-hotels.com\/bourgogne\/wp-content\/uploads\/sites\/5\/2026\/04\/SDV_LAubergedesCiteaux_\u00a9AgencePancake-11.jpg 1920w\" sizes=\"auto, (max-width: 1725px) 100vw, 1725px\" \/>                <\/figure>\n\n                <h3 class=\"font-serif\">\n                    L\u2019Auberge des C\u00eeteaux                <\/h3>\n\n                                    <div class=\"mt-[13rem]\">\n                        <p>L\u2019Auberge des C\u00eeteaux vous invite \u00e0 d\u00e9couvrir une cuisine bourguignonne authentique et g\u00e9n\u00e9reuse, sublim\u00e9e par le savoir-faire du chef Julien Martin.<\/p>\n                    <\/div>\n                \n                                    <a href=\"https:\/\/www.sources-hotels.com\/bourgogne\/restaurant-lauberge-des-citeaux\/\" class=\"link mt-[10rem] tablet:mt-[20rem]\" target=\"\">\n                        D\u00e9couvrir                    <\/a>\n                \n            <\/div>\n\n        \n            <div class=\"slide w-[200rem] tablet:w-[450rem] teaser teaser--article-type-1\">\n\n                \n                <figure class=\"w-full h-[240rem] mb-[5rem] tablet:h-[575rem] tablet:mb-[30rem]\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"1725\" height=\"1150\" src=\"https:\/\/www.sources-hotels.com\/bourgogne\/wp-content\/uploads\/sites\/5\/2026\/04\/SDV_BarduChateau_\u00a9AgencePancake-11-1-1725x1150.jpg\" class=\"h-full w-full object-cover object-center lightgallery-item\" alt=\"Bar du Ch\u00e2teau - Les Sources de Vougeot\" data-src=\"https:\/\/www.sources-hotels.com\/bourgogne\/wp-content\/uploads\/sites\/5\/2026\/04\/SDV_BarduChateau_\u00a9AgencePancake-11-1.jpg\" srcset=\"https:\/\/www.sources-hotels.com\/bourgogne\/wp-content\/uploads\/sites\/5\/2026\/04\/SDV_BarduChateau_\u00a9AgencePancake-11-1-1725x1150.jpg 1725w, https:\/\/www.sources-hotels.com\/bourgogne\/wp-content\/uploads\/sites\/5\/2026\/04\/SDV_BarduChateau_\u00a9AgencePancake-11-1-300x200.jpg 300w, https:\/\/www.sources-hotels.com\/bourgogne\/wp-content\/uploads\/sites\/5\/2026\/04\/SDV_BarduChateau_\u00a9AgencePancake-11-1-1024x683.jpg 1024w, https:\/\/www.sources-hotels.com\/bourgogne\/wp-content\/uploads\/sites\/5\/2026\/04\/SDV_BarduChateau_\u00a9AgencePancake-11-1-768x512.jpg 768w, https:\/\/www.sources-hotels.com\/bourgogne\/wp-content\/uploads\/sites\/5\/2026\/04\/SDV_BarduChateau_\u00a9AgencePancake-11-1-1536x1024.jpg 1536w, https:\/\/www.sources-hotels.com\/bourgogne\/wp-content\/uploads\/sites\/5\/2026\/04\/SDV_BarduChateau_\u00a9AgencePancake-11-1.jpg 1920w\" sizes=\"auto, (max-width: 1725px) 100vw, 1725px\" \/>                <\/figure>\n\n                <h3 class=\"font-serif\">\n                    Le Bar du Ch\u00e2teau                <\/h3>\n\n                                    <div class=\"mt-[13rem]\">\n                        <p>Situ\u00e9 au c\u0153ur du Ch\u00e2teau de Gilly, le Bar du Ch\u00e2teau est un lieu de d\u00e9gustation et de partage.<\/p>\n                    <\/div>\n                \n                \n            <\/div>\n\n        \n            <div class=\"slide w-[200rem] tablet:w-[450rem] teaser teaser--article-type-1\">\n\n                \n                <figure class=\"w-full h-[240rem] mb-[5rem] tablet:h-[575rem] tablet:mb-[30rem]\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"767\" height=\"1150\" src=\"https:\/\/www.sources-hotels.com\/bourgogne\/wp-content\/uploads\/sites\/5\/2026\/04\/LesSourcesdeVougeot_LOrangerie_\u00a9MaximilienForgetStudio-4-767x1150.jpg\" class=\"h-full w-full object-cover object-center lightgallery-item\" alt=\"Petit d\u00e9jeuner l&#039;Orangerie - Les Sources de Vougeot\" data-src=\"https:\/\/www.sources-hotels.com\/bourgogne\/wp-content\/uploads\/sites\/5\/2026\/04\/LesSourcesdeVougeot_LOrangerie_\u00a9MaximilienForgetStudio-4.jpg\" srcset=\"https:\/\/www.sources-hotels.com\/bourgogne\/wp-content\/uploads\/sites\/5\/2026\/04\/LesSourcesdeVougeot_LOrangerie_\u00a9MaximilienForgetStudio-4-767x1150.jpg 767w, https:\/\/www.sources-hotels.com\/bourgogne\/wp-content\/uploads\/sites\/5\/2026\/04\/LesSourcesdeVougeot_LOrangerie_\u00a9MaximilienForgetStudio-4-200x300.jpg 200w, https:\/\/www.sources-hotels.com\/bourgogne\/wp-content\/uploads\/sites\/5\/2026\/04\/LesSourcesdeVougeot_LOrangerie_\u00a9MaximilienForgetStudio-4-683x1024.jpg 683w, https:\/\/www.sources-hotels.com\/bourgogne\/wp-content\/uploads\/sites\/5\/2026\/04\/LesSourcesdeVougeot_LOrangerie_\u00a9MaximilienForgetStudio-4-768x1152.jpg 768w, https:\/\/www.sources-hotels.com\/bourgogne\/wp-content\/uploads\/sites\/5\/2026\/04\/LesSourcesdeVougeot_LOrangerie_\u00a9MaximilienForgetStudio-4-1024x1536.jpg 1024w, https:\/\/www.sources-hotels.com\/bourgogne\/wp-content\/uploads\/sites\/5\/2026\/04\/LesSourcesdeVougeot_LOrangerie_\u00a9MaximilienForgetStudio-4.jpg 1280w\" sizes=\"auto, (max-width: 767px) 100vw, 767px\" \/>                <\/figure>\n\n                <h3 class=\"font-serif\">\n                    L&rsquo;Orangerie                <\/h3>\n\n                                    <div class=\"mt-[13rem]\">\n                        <div class=\"qMYqUG_convSearchResultHighlightRoot\">\n<div class=\"\" data-turn-id-container=\"request-WEB:82bc5f45-88d4-43cd-8cba-f7cb369283d0-11\" data-is-intersecting=\"true\">\n<section class=\"text-token-text-primary w-full focus:outline-none has-data-writing-block:pointer-events-none [&amp;:has([data-writing-block])&gt;*]:pointer-events-auto R6Vx5W_threadScrollVars scroll-mb-[calc(var(--scroll-root-safe-area-inset-bottom,0px)+var(--thread-response-height))] scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" data-turn-id=\"request-WEB:82bc5f45-88d4-43cd-8cba-f7cb369283d0-11\" data-turn-id-container=\"request-WEB:82bc5f45-88d4-43cd-8cba-f7cb369283d0-11\" data-testid=\"conversation-turn-24\" data-scroll-anchor=\"false\" data-turn=\"assistant\">\n<div class=\"text-base my-auto mx-auto pb-10 [--thread-content-margin:var(--thread-content-margin-xs,calc(var(--spacing)*4))] @w-sm\/main:[--thread-content-margin:var(--thread-content-margin-sm,calc(var(--spacing)*6))] @w-lg\/main:[--thread-content-margin:var(--thread-content-margin-lg,calc(var(--spacing)*16))] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:40rem] @w-lg\/main:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\" data-conversation-screenshot-content=\"\">\n<div class=\"flex max-w-full flex-col gap-4 grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal outline-none keyboard-focused:focus-ring [.text-message+&amp;]:mt-1\" dir=\"auto\" tabindex=\"0\" data-message-author-role=\"assistant\" data-message-id=\"d326f5de-bb15-4a3d-956c-9192321c42e0\" data-message-model-slug=\"gpt-5-5\" data-turn-start-message=\"true\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden\">\n<div class=\"markdown prose dark:prose-invert wrap-break-word w-full light markdown-new-styling\">\n<p data-start=\"0\" data-end=\"125\" data-is-last-node=\"\" data-is-only-node=\"\">Baign\u00e9e de lumi\u00e8re, L\u2019Orangerie est un espace de convivialit\u00e9 et de d\u00e9tente qui accueille les petits-d\u00e9jeuners dans un cadre ouvert sur la nature.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"z-0 flex min-h-[46px] justify-start\"><\/div>\n<div class=\"mt-3 w-full empty:hidden\">\n<div class=\"text-center\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n<\/div>\n<div class=\"pointer-events-none -mt-px h-px translate-y-[calc(var(--scroll-root-safe-area-inset-bottom)-14*var(--spacing))]\" aria-hidden=\"true\"><\/div>\n                    <\/div>\n                \n                \n            <\/div>\n\n        \n    <\/div>\n\n    \n<\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":12,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"hotels":[],"doc_cat":[],"class_list":["post-6438","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Restaurant Le Clos de la Tour - Les Sources de Vougeot<\/title>\n<meta name=\"description\" content=\"Restaurant gastronomique \u00e0 2 pas du Ch\u00e2teau du Clos de Vougeot. Chef Julien Martin. Accord mets et vins. R\u00e9servation en ligne\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sources-hotels.com\/bourgogne\/restaurant-le-clos-de-la-tour\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Restaurant Le Clos de la Tour - Les Sources de Vougeot\" \/>\n<meta property=\"og:description\" content=\"Restaurant gastronomique \u00e0 2 pas du Ch\u00e2teau du Clos de Vougeot. Chef Julien Martin. Accord mets et vins. R\u00e9servation en ligne\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sources-hotels.com\/bourgogne\/restaurant-le-clos-de-la-tour\/\" \/>\n<meta property=\"og:site_name\" content=\"Les Sources de Vougeot\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-07T13:24:28+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sources-hotels.com\\\/bourgogne\\\/restaurant-le-clos-de-la-tour\\\/\",\"url\":\"https:\\\/\\\/www.sources-hotels.com\\\/bourgogne\\\/restaurant-le-clos-de-la-tour\\\/\",\"name\":\"Restaurant Le Clos de la Tour - Les Sources de Vougeot\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sources-hotels.com\\\/bourgogne\\\/#website\"},\"datePublished\":\"2026-02-16T13:44:10+00:00\",\"dateModified\":\"2026-08-07T13:24:28+00:00\",\"description\":\"Restaurant gastronomique \u00e0 2 pas du Ch\u00e2teau du Clos de Vougeot. Chef Julien Martin. Accord mets et vins. R\u00e9servation en ligne\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sources-hotels.com\\\/bourgogne\\\/restaurant-le-clos-de-la-tour\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sources-hotels.com\\\/bourgogne\\\/restaurant-le-clos-de-la-tour\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sources-hotels.com\\\/bourgogne\\\/restaurant-le-clos-de-la-tour\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.sources-hotels.com\\\/bourgogne\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Restaurant Le Clos de la Tour\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sources-hotels.com\\\/bourgogne\\\/#website\",\"url\":\"https:\\\/\\\/www.sources-hotels.com\\\/bourgogne\\\/\",\"name\":\"Les Sources de Vougeot\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sources-hotels.com\\\/bourgogne\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sources-hotels.com\\\/bourgogne\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sources-hotels.com\\\/bourgogne\\\/#organization\",\"name\":\"Les Sources de Vougeot\",\"url\":\"https:\\\/\\\/www.sources-hotels.com\\\/bourgogne\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.sources-hotels.com\\\/bourgogne\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Les Sources de Vougeot\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sources-hotels.com\\\/bourgogne\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Restaurant Le Clos de la Tour - Les Sources de Vougeot","description":"Restaurant gastronomique \u00e0 2 pas du Ch\u00e2teau du Clos de Vougeot. Chef Julien Martin. Accord mets et vins. R\u00e9servation en ligne","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sources-hotels.com\/bourgogne\/restaurant-le-clos-de-la-tour\/","og_locale":"fr_FR","og_type":"article","og_title":"Restaurant Le Clos de la Tour - Les Sources de Vougeot","og_description":"Restaurant gastronomique \u00e0 2 pas du Ch\u00e2teau du Clos de Vougeot. Chef Julien Martin. Accord mets et vins. R\u00e9servation en ligne","og_url":"https:\/\/www.sources-hotels.com\/bourgogne\/restaurant-le-clos-de-la-tour\/","og_site_name":"Les Sources de Vougeot","article_modified_time":"2026-08-07T13:24:28+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.sources-hotels.com\/bourgogne\/restaurant-le-clos-de-la-tour\/","url":"https:\/\/www.sources-hotels.com\/bourgogne\/restaurant-le-clos-de-la-tour\/","name":"Restaurant Le Clos de la Tour - Les Sources de Vougeot","isPartOf":{"@id":"https:\/\/www.sources-hotels.com\/bourgogne\/#website"},"datePublished":"2026-02-16T13:44:10+00:00","dateModified":"2026-08-07T13:24:28+00:00","description":"Restaurant gastronomique \u00e0 2 pas du Ch\u00e2teau du Clos de Vougeot. Chef Julien Martin. Accord mets et vins. R\u00e9servation en ligne","breadcrumb":{"@id":"https:\/\/www.sources-hotels.com\/bourgogne\/restaurant-le-clos-de-la-tour\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sources-hotels.com\/bourgogne\/restaurant-le-clos-de-la-tour\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sources-hotels.com\/bourgogne\/restaurant-le-clos-de-la-tour\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.sources-hotels.com\/bourgogne\/"},{"@type":"ListItem","position":2,"name":"Restaurant Le Clos de la Tour"}]},{"@type":"WebSite","@id":"https:\/\/www.sources-hotels.com\/bourgogne\/#website","url":"https:\/\/www.sources-hotels.com\/bourgogne\/","name":"Les Sources de Vougeot","description":"","publisher":{"@id":"https:\/\/www.sources-hotels.com\/bourgogne\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sources-hotels.com\/bourgogne\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.sources-hotels.com\/bourgogne\/#organization","name":"Les Sources de Vougeot","url":"https:\/\/www.sources-hotels.com\/bourgogne\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.sources-hotels.com\/bourgogne\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Les Sources de Vougeot"},"image":{"@id":"https:\/\/www.sources-hotels.com\/bourgogne\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.sources-hotels.com\/bourgogne\/wp-json\/wp\/v2\/pages\/6438","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sources-hotels.com\/bourgogne\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.sources-hotels.com\/bourgogne\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.sources-hotels.com\/bourgogne\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sources-hotels.com\/bourgogne\/wp-json\/wp\/v2\/comments?post=6438"}],"version-history":[{"count":82,"href":"https:\/\/www.sources-hotels.com\/bourgogne\/wp-json\/wp\/v2\/pages\/6438\/revisions"}],"predecessor-version":[{"id":10080,"href":"https:\/\/www.sources-hotels.com\/bourgogne\/wp-json\/wp\/v2\/pages\/6438\/revisions\/10080"}],"wp:attachment":[{"href":"https:\/\/www.sources-hotels.com\/bourgogne\/wp-json\/wp\/v2\/media?parent=6438"}],"wp:term":[{"taxonomy":"hotels","embeddable":true,"href":"https:\/\/www.sources-hotels.com\/bourgogne\/wp-json\/wp\/v2\/hotels?post=6438"},{"taxonomy":"doc_cat","embeddable":true,"href":"https:\/\/www.sources-hotels.com\/bourgogne\/wp-json\/wp\/v2\/doc_cat?post=6438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}